{"id":4560,"date":"2022-02-03T22:04:10","date_gmt":"2022-02-03T22:04:10","guid":{"rendered":"https:\/\/leondeoro.com\/product\/red-porteria-cajon-hockey-sala\/"},"modified":"2022-05-02T15:06:41","modified_gmt":"2022-05-02T15:06:41","slug":"red-porteria-cajon-hockey-sala","status":"publish","type":"product","link":"https:\/\/leondeoro.com\/de\/produkt\/red-porteria-cajon-hockey-sala\/","title":{"rendered":"Hallenhockeynetz"},"content":{"rendered":"<p>3 m lang x 2 m hoch x 0,80 m oben x 1 m unten x 1 m unten<\/p>\n","protected":false},"excerpt":{"rendered":"<p>3 m lang x 2 m hoch x 0,80 m oben x 1 m unten x 1 m unten<\/p>\n","protected":false},"featured_media":6881,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[463,455],"product_tag":[],"class_list":{"0":"post-4560","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-hockey-de","7":"product_cat-sportnetze","9":"first","10":"instock","11":"shipping-taxable","12":"purchasable","13":"product-type-variable","14":"has-default-attributes"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hallenhockeynetz - Le\u00f3n de Oro<\/title>\n<meta name=\"description\" content=\"Wir fertigen Netze f\u00fcr Hallenhockeytore mit einem Ballfangvorhang, der die Energie des Balls absorbiert und ihn im Tor h\u00e4lt.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leondeoro.com\/produkt\/red-porteria-cajon-hockey-sala\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hallenhockeynetz - Le\u00f3n de Oro\" \/>\n<meta property=\"og:description\" content=\"Wir fertigen Netze f\u00fcr Hallenhockeytore mit einem Ballfangvorhang, der die Energie des Balls absorbiert und ihn im Tor h\u00e4lt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leondeoro.com\/produkt\/red-porteria-cajon-hockey-sala\/\" \/>\n<meta property=\"og:site_name\" content=\"Le\u00f3n de Oro\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-02T15:06:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/leondeoro.com\/wp-content\/uploads\/2022\/02\/hockey-hierba_4-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1709\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/leondeoro.com\\\/produkt\\\/red-porteria-cajon-hockey-sala\\\/\",\"url\":\"https:\\\/\\\/leondeoro.com\\\/produkt\\\/red-porteria-cajon-hockey-sala\\\/\",\"name\":\"Hallenhockeynetz - Le\u00f3n de Oro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leondeoro.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/leondeoro.com\\\/produkt\\\/red-porteria-cajon-hockey-sala\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/leondeoro.com\\\/produkt\\\/red-porteria-cajon-hockey-sala\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leondeoro.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/hockey-hierba_4-1-scaled.jpg\",\"datePublished\":\"2022-02-03T22:04:10+00:00\",\"dateModified\":\"2022-05-02T15:06:41+00:00\",\"description\":\"Wir fertigen Netze f\u00fcr Hallenhockeytore mit einem Ballfangvorhang, der die Energie des Balls absorbiert und ihn im Tor h\u00e4lt.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leondeoro.com\\\/produkt\\\/red-porteria-cajon-hockey-sala\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/leondeoro.com\\\/produkt\\\/red-porteria-cajon-hockey-sala\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/leondeoro.com\\\/produkt\\\/red-porteria-cajon-hockey-sala\\\/#primaryimage\",\"url\":\"https:\\\/\\\/leondeoro.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/hockey-hierba_4-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/leondeoro.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/hockey-hierba_4-1-scaled.jpg\",\"width\":2560,\"height\":1709,\"caption\":\"hockey\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leondeoro.com\\\/produkt\\\/red-porteria-cajon-hockey-sala\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/leondeoro.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/leondeoro.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hallenhockeynetz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leondeoro.com\\\/#website\",\"url\":\"https:\\\/\\\/leondeoro.com\\\/\",\"name\":\"Le\u00f3n de Oro\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leondeoro.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hallenhockeynetz - Le\u00f3n de Oro","description":"Wir fertigen Netze f\u00fcr Hallenhockeytore mit einem Ballfangvorhang, der die Energie des Balls absorbiert und ihn im Tor h\u00e4lt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leondeoro.com\/produkt\/red-porteria-cajon-hockey-sala\/","og_locale":"de_DE","og_type":"article","og_title":"Hallenhockeynetz - Le\u00f3n de Oro","og_description":"Wir fertigen Netze f\u00fcr Hallenhockeytore mit einem Ballfangvorhang, der die Energie des Balls absorbiert und ihn im Tor h\u00e4lt.","og_url":"https:\/\/leondeoro.com\/produkt\/red-porteria-cajon-hockey-sala\/","og_site_name":"Le\u00f3n de Oro","article_modified_time":"2022-05-02T15:06:41+00:00","og_image":[{"width":2560,"height":1709,"url":"https:\/\/leondeoro.com\/wp-content\/uploads\/2022\/02\/hockey-hierba_4-1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/leondeoro.com\/produkt\/red-porteria-cajon-hockey-sala\/","url":"https:\/\/leondeoro.com\/produkt\/red-porteria-cajon-hockey-sala\/","name":"Hallenhockeynetz - Le\u00f3n de Oro","isPartOf":{"@id":"https:\/\/leondeoro.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/leondeoro.com\/produkt\/red-porteria-cajon-hockey-sala\/#primaryimage"},"image":{"@id":"https:\/\/leondeoro.com\/produkt\/red-porteria-cajon-hockey-sala\/#primaryimage"},"thumbnailUrl":"https:\/\/leondeoro.com\/wp-content\/uploads\/2022\/02\/hockey-hierba_4-1-scaled.jpg","datePublished":"2022-02-03T22:04:10+00:00","dateModified":"2022-05-02T15:06:41+00:00","description":"Wir fertigen Netze f\u00fcr Hallenhockeytore mit einem Ballfangvorhang, der die Energie des Balls absorbiert und ihn im Tor h\u00e4lt.","breadcrumb":{"@id":"https:\/\/leondeoro.com\/produkt\/red-porteria-cajon-hockey-sala\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leondeoro.com\/produkt\/red-porteria-cajon-hockey-sala\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/leondeoro.com\/produkt\/red-porteria-cajon-hockey-sala\/#primaryimage","url":"https:\/\/leondeoro.com\/wp-content\/uploads\/2022\/02\/hockey-hierba_4-1-scaled.jpg","contentUrl":"https:\/\/leondeoro.com\/wp-content\/uploads\/2022\/02\/hockey-hierba_4-1-scaled.jpg","width":2560,"height":1709,"caption":"hockey"},{"@type":"BreadcrumbList","@id":"https:\/\/leondeoro.com\/produkt\/red-porteria-cajon-hockey-sala\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/leondeoro.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/leondeoro.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Hallenhockeynetz"}]},{"@type":"WebSite","@id":"https:\/\/leondeoro.com\/#website","url":"https:\/\/leondeoro.com\/","name":"Le\u00f3n de Oro","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leondeoro.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/leondeoro.com\/de\/wp-json\/wp\/v2\/product\/4560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leondeoro.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/leondeoro.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/leondeoro.com\/de\/wp-json\/wp\/v2\/comments?post=4560"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leondeoro.com\/de\/wp-json\/wp\/v2\/media\/6881"}],"wp:attachment":[{"href":"https:\/\/leondeoro.com\/de\/wp-json\/wp\/v2\/media?parent=4560"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/leondeoro.com\/de\/wp-json\/wp\/v2\/product_brand?post=4560"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/leondeoro.com\/de\/wp-json\/wp\/v2\/product_cat?post=4560"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/leondeoro.com\/de\/wp-json\/wp\/v2\/product_tag?post=4560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}